{"id":996,"date":"2014-04-18T18:36:33","date_gmt":"2014-04-18T16:36:33","guid":{"rendered":"http:\/\/www.freie-schwimmer-bochum.de\/FSB_Blog\/?p=996"},"modified":"2023-10-11T07:52:37","modified_gmt":"2023-10-11T05:52:37","slug":"wir-wuenschen-ein-frohes-osterfest-2","status":"publish","type":"post","link":"http:\/\/www.freie-schwimmer-bochum.de\/FSB_Blog\/wir-wuenschen-ein-frohes-osterfest-2\/","title":{"rendered":"Wir w\u00fcnschen ein frohes Osterfest!"},"content":{"rendered":"<div class=\"twoclick_social_bookmarks_post_996 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_996')){$('.twoclick_social_bookmarks_post_996').socialSharePrivacy({\"services\":{\"facebook\":{\"status\":\"on\",\"txt_info\":\"2 Klicks f\\u00fcr mehr Datenschutz: Erst wenn Sie hier klicken, wird der Button aktiv und Sie k\\u00f6nnen Ihre Empfehlung an Facebook senden. Schon beim Aktivieren werden Daten an Dritte \\u00fcbertragen - siehe <em>i<\\\/em>.\",\"perma_option\":\"off\",\"action\":\"like\",\"language\":\"de_DE\"}},\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"http:\\\/\\\/www.freie-schwimmer-bochum.de\\\/FSB_Blog\\\/wir-wuenschen-ein-frohes-osterfest-2\\\/\",\"post_id\":996,\"post_title_referrer_track\":\"Wir+w%C3%BCnschen+ein+frohes+Osterfest%21\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[17],"tags":[],"class_list":["post-996","post","type-post","status-publish","format-standard","hentry","category-allgemein","nodate","item-wrap"],"_links":{"self":[{"href":"http:\/\/www.freie-schwimmer-bochum.de\/FSB_Blog\/wp-json\/wp\/v2\/posts\/996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.freie-schwimmer-bochum.de\/FSB_Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.freie-schwimmer-bochum.de\/FSB_Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.freie-schwimmer-bochum.de\/FSB_Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.freie-schwimmer-bochum.de\/FSB_Blog\/wp-json\/wp\/v2\/comments?post=996"}],"version-history":[{"count":0,"href":"http:\/\/www.freie-schwimmer-bochum.de\/FSB_Blog\/wp-json\/wp\/v2\/posts\/996\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.freie-schwimmer-bochum.de\/FSB_Blog\/wp-json\/wp\/v2\/media?parent=996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.freie-schwimmer-bochum.de\/FSB_Blog\/wp-json\/wp\/v2\/categories?post=996"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.freie-schwimmer-bochum.de\/FSB_Blog\/wp-json\/wp\/v2\/tags?post=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}